{"id":24407,"date":"2025-12-20T08:00:00","date_gmt":"2025-12-20T13:00:00","guid":{"rendered":"https:\/\/www.cufoundation.ca\/its-the-season-to-share\/"},"modified":"2025-12-22T11:40:45","modified_gmt":"2025-12-22T16:40:45","slug":"its-the-season-to-share","status":"publish","type":"post","link":"https:\/\/www.cufoundation.ca\/fr\/its-the-season-to-share\/","title":{"rendered":"En\u00a0cette\u00a0saison, la g\u00e9n\u00e9rosit\u00e9 prend tout son sens"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\"><strong><em>Ensemble,\u00a0partageons\u00a0un peu de lumi\u00e8re durant\u00a0les F\u00eates<\/em><\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/wl.donorperfect.net\/weblink\/weblink.aspx?name=E357368QE&amp;id=56\" style=\"background-color:#be1c09\" target=\"_blank\" rel=\"noopener\">FAITES UN DON<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Alors que les Ukrainiens subissent une fois de plus la dure r\u00e9alit\u00e9 de l\u2019hiver, aggrav\u00e9e par des pannes de courant caus\u00e9es par les attaques incessantes de drones et de missiles russes, un don \u00e0 la\u00a0<a href=\"https:\/\/weblink.donorperfect.com\/CUFHolidayCampaign2025\" target=\"_blank\" rel=\"noreferrer noopener\">Campagne des F\u00eates<\/a>\u00a0est une occasion d\u2019apporter lumi\u00e8re et chaleur l\u00e0 o\u00f9 elles sont le plus n\u00e9cessaires. Chaque dollar vers\u00e9 \u00e0 l\u2019<strong>Appel humanitaire Canada-Ukraine de la FCU et du CUC<\/strong>\u00a0fait r\u00e9ellement une diff\u00e9rence, en aidant \u00e0 fournir de l\u2019\u00e9lectricit\u00e9 et un soutien essentiel.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u2728\u00a0<strong>Nous aimerions\u00a0partager\u00a0un peu de\u00a0magie\u00a0des F\u00eates avec\u00a0vous\u00a0!\u00a0<\/strong>\u2728<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En faisant un don \u00e0 la campagne\u00a0entre le 20 et le 31\u00a0d\u00e9cembre, vous pourriez recevoir l\u2019un des cadeaux suivants g\u00e9n\u00e9reusement offerts par nos partenaires en guise de remerciement.<\/p>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 34%\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong><strong>Une bo\u00eete-cadeau \u00ab\u00a0Coffret coup de c\u0153ur\u00a0\u00bb de Zirkova, compos\u00e9e d\u2019articles soigneusement s\u00e9lectionn\u00e9s par ses fondateurs, John et Katherine Vellinga<\/strong><\/strong><\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/Zirkova_holidaybox-2-819x1024.jpg\" alt=\"\" class=\"wp-image-24400 size-full\" srcset=\"https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/Zirkova_holidaybox-2-819x1024.jpg 819w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/Zirkova_holidaybox-2-240x300.jpg 240w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/Zirkova_holidaybox-2-768x960.jpg 768w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/Zirkova_holidaybox-2.jpg 1200w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:34% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/1080x1350-Meest-ad-2025-819x1024.jpg\" alt=\"\" class=\"wp-image-24403 size-full\" srcset=\"https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/1080x1350-Meest-ad-2025-819x1024.jpg 819w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/1080x1350-Meest-ad-2025-240x300.jpg 240w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/1080x1350-Meest-ad-2025-768x960.jpg 768w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/1080x1350-Meest-ad-2025.jpg 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong><strong>Coffret-cadeau VIP exclusif offert par Meest Canada avec envois gratuits vers les destinations admissibles<\/strong><\/strong><\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u2728&nbsp;<strong>Merci \u00e0 nos partenaires&nbsp;<\/strong>\u2728<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">\ufeffFond\u00e9e en 2004,&nbsp;<a href=\"https:\/\/www.zirkova.com\/\" rel=\"noreferrer noopener\" target=\"_blank\">Zirkova<\/a>&nbsp;est une entreprise ukraino-canadienne d\u00e9di\u00e9e \u00e0 faire rayonner l\u2019Ukraine sur la sc\u00e8ne mondiale. Depuis le d\u00e9but de la guerre, Zirkova s\u2019est activement engag\u00e9e \u00e0 sensibiliser le public et a contribu\u00e9 \u00e0 hauteur de plus de 25 000 $ \u00e0 des efforts humanitaires soutenant les Ukrainiens sur le terrain. Malgr\u00e9 les perturbations continues de la production et de la distribution, l\u2019entreprise reste d\u00e9termin\u00e9e \u00e0 produire en Ukraine et \u00e0 soutenir l\u2019\u00e9conomie locale. En plus d\u2019\u00eatre les fondateurs de Zirkova Vodka, ils distribuent \u00e9galement les vins mousseux Victory White Brut, Red Semi-Sweet et Demi-Sec Ros\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fond\u00e9e \u00e0 Toronto en 1989,\u00a0<a href=\"https:\/\/ca.meest.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Meest Canada<\/a>\u00a0est un partenaire de confiance en logistique transfrontali\u00e8re et en commerce \u00e9lectronique, reliant les entreprises canadiennes \u00e0 plus de 214 destinations \u00e0 travers le monde. Profond\u00e9ment ancr\u00e9e dans la communaut\u00e9 canado-ukrainienne et forte de partenariats de longue date avec des transporteurs internationaux et les autorit\u00e9s douani\u00e8res, l\u2019entreprise offre des solutions fiables, \u00e9volutives et rentables, notamment en mati\u00e8re d\u2019exp\u00e9dition de colis et de marchandises, de services de traitement des commandes pour le commerce \u00e9lectronique, de solutions logistiques B2B et de transferts internationaux de fonds.<\/p>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 34%\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong>Nous rappelons que gr\u00e2ce \u00e0 la Fondation de la famille Myhal, vos dons seront jumel\u00e9s jusqu\u2019au 12 janvier, et ce, jusqu\u2019\u00e0 concurrence de 1&nbsp;000&nbsp;000&nbsp;$.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ensemble, nous pouvons transformer l\u2019esprit de g\u00e9n\u00e9rosit\u00e9 en un espoir concret et tangible pour ceux qui en ont le plus besoin.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>JOIGNEZ-VOUS \u00c0 NOUS&nbsp;!<\/strong><\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/CUF_MYHAL-GIFT_FRA-META_SQUARE-1024x1024.png\" alt=\"\" class=\"wp-image-24349 size-full\" srcset=\"https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/CUF_MYHAL-GIFT_FRA-META_SQUARE-1024x1024.png 1024w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/CUF_MYHAL-GIFT_FRA-META_SQUARE-300x300.png 300w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/CUF_MYHAL-GIFT_FRA-META_SQUARE-150x150.png 150w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/CUF_MYHAL-GIFT_FRA-META_SQUARE-768x768.png 768w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2025\/12\/CUF_MYHAL-GIFT_FRA-META_SQUARE.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/wl.donorperfect.net\/weblink\/weblink.aspx?name=E357368QE&amp;id=56\" style=\"background-color:#be1c09\" target=\"_blank\" rel=\"noopener\">FAITES UN DON<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Pour faire un don \u00e0 notre Campagne des f\u00eates avec AMEX, PayPal ou Google Pay,\u00a0<\/strong><a href=\"https:\/\/www.canadahelps.org\/fr\/dn\/70605\" target=\"_blank\" rel=\"noreferrer noopener\">veuillez visiter notre page CanadaHelps.<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>\u00c0 propos de l\u2019Appel humanitaire pour l\u2019Ukraine de la FCU et du CUC<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lanc\u00e9 en janvier 2022 \u00e0 titre d\u2019initiative conjointe de la Fondation Canada-Ukraine (FCU) et du Congr\u00e8s des Ukrainiens Canadiens (CUC), l\u2019Appel humanitaire pour l\u2019Ukraine de la FCU et du CUC (AHU) coordonne la prestation efficace de l\u2019aide humanitaire en r\u00e9ponse \u00e0 l\u2019invasion \u00e0 grande \u00e9chelle de l\u2019Ukraine par la Russie. Ses efforts soutiennent les personnes d\u00e9plac\u00e9es, les soins m\u00e9dicaux, l\u2019h\u00e9bergement d\u2019urgence et la s\u00e9curit\u00e9 alimentaire, tant en Ukraine que parmi ceux et celles qui ont trouv\u00e9 refuge ailleurs en Europe et au Canada. \u00c0 ce jour, pr\u00e8s de 100&nbsp;millions de dollars en aide humanitaire ont \u00e9t\u00e9 d\u00e9ploy\u00e9s, apportant un soutien essentiel \u00e0 plus de 6\u202fmillions de personnes par l\u2019entremise de plus de 300 projets.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>\u00c0 propos de la Fondation Canada-Ukraine&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Fond\u00e9e en 1995 lors du 18e Congr\u00e8s des Ukrainiens-Canadiens (CUC), la Fondation Canada-Ukraine (FCU) a \u00e9t\u00e9 cr\u00e9\u00e9e pour coordonner, d\u00e9velopper et fournir de l&rsquo;aide humanitaire de la part des Canadiennes et Canadiens \u00e0 l&rsquo;attention de l\u2019Ukraine. La FCU continue de jouer un r\u00f4le essentiel en tant qu\u2019organisme de bienfaisance national, dont l\u2019objectif est de surveiller, promouvoir et soutenir des initiatives d&rsquo;aide humanitaire. Sa mission consiste entre autres \u00e0 \u00e9valuer des projets, favoriser la collaboration entre les organismes fournissant de l&rsquo;aide, \u00e9tablir des priorit\u00e9s strat\u00e9giques et s&rsquo;assurer que les ressources soient affect\u00e9es \u00e0 des domaines o\u00f9 leur port\u00e9e puisse \u00eatre maximis\u00e9e. La FCU assure \u00e9galement un r\u00f4le de lieu d\u2019\u00e9change pour les personnes et organismes des secteurs communautaire, priv\u00e9 et public qui ont \u00e0 c\u0153ur de soutenir l&rsquo;Ukraine. Outre son action \u00e0 l&rsquo;\u00e9tranger, la FCU appuie \u00e9galement des initiatives li\u00e9es \u00e0 ces objectifs et activit\u00e9s au Canada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ensemble,\u00a0partageons\u00a0un peu de lumi\u00e8re durant\u00a0les F\u00eates Alors que les Ukrainiens subissent une fois de plus la dure r\u00e9alit\u00e9 de l\u2019hiver, aggrav\u00e9e par des pannes de courant caus\u00e9es par les attaques incessantes de drones et de missiles russes, un don \u00e0 la\u00a0Campagne des F\u00eates\u00a0est une occasion d\u2019apporter lumi\u00e8re et chaleur l\u00e0 o\u00f9 elles sont le plus [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":24411,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[67],"tags":[],"class_list":["post-24407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-fr"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 06:36:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts\/24407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/comments?post=24407"}],"version-history":[{"count":1,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts\/24407\/revisions"}],"predecessor-version":[{"id":24409,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts\/24407\/revisions\/24409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/media\/24411"}],"wp:attachment":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/media?parent=24407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/categories?post=24407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/tags?post=24407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}