{"id":26321,"date":"2026-05-17T08:00:00","date_gmt":"2026-05-17T12:00:00","guid":{"rendered":"https:\/\/www.cufoundation.ca\/?p=26321"},"modified":"2026-05-15T19:17:24","modified_gmt":"2026-05-15T23:17:24","slug":"preserving-ukraines-identity-and-hope","status":"publish","type":"post","link":"https:\/\/www.cufoundation.ca\/fr\/preserving-ukraines-identity-and-hope\/","title":{"rendered":"Pr\u00e9server l\u2019identit\u00e9 et l\u2019espoir de l\u2019Ukraine"},"content":{"rendered":"\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background-color has-text-color has-background has-link-color wp-element-button\" href=\"http:\/\/weblink.donorperfect.com\/HumanDimension2026\" style=\"background-color:#be1c09\" target=\"_blank\" rel=\"noopener\">FAITES UN DON<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Les 13 et 14 mai, pendant plus de 48 heures, la Russie a men\u00e9 l&rsquo;une des attaques a\u00e9riennes les plus longues et les plus intenses depuis le d\u00e9but de l&rsquo;invasion \u00e0 grande \u00e9chelle en 2022. Pr\u00e8s de 1\u00a0600 drones et 60 missiles ont pris pour cible plus de 20 r\u00e9gions d\u2019Ukraine.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"http:\/\/weblink.donorperfect.com\/HumanDimension2026\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/05\/Kyiv_May14_photo-1.png\" alt=\"\" class=\"wp-image-26317\" srcset=\"https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/05\/Kyiv_May14_photo-1.png 960w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/05\/Kyiv_May14_photo-1-300x200.png 300w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/05\/Kyiv_May14_photo-1-768x512.png 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><figcaption class=\"wp-element-caption\">[Op\u00e9rations de recherche et de sauvetage \u00e0 Kyiv le 14 mai 2026, apr\u00e8s l\u2019attaque a\u00e9rienne russe de grande envergure. Cr\u00e9dit photo : Service national des situations d\u2019urgence de l\u2019Ukraine]\u00a0<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Les reportages mettent l&rsquo;accent sur les destructions et les d\u00e9placements caus\u00e9s par la guerre. Mais derri\u00e8re chaque manchette et chaque statistique se cachent aussi des histoires humaines qui parlent de r\u00e9silience, d&rsquo;identit\u00e9, de culture et d&rsquo;espoir.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udfa5\u00a0Nous vous invitons \u00e0 regarder cette courte vid\u00e9o avec Olesia Luciw-Andryjowycz, secr\u00e9taire de notre Conseil d\u2019administration et pr\u00e9sidente de notre Comit\u00e9 pour la soci\u00e9t\u00e9 civile, pr\u00e9sentant des membres de la communit\u00e9 ukrainienne canadienne qui contribuent \u00e0 pr\u00e9server la culture, l&rsquo;identit\u00e9 et l&rsquo;esprit de l&rsquo;Ukraine face \u00e0 la guerre que m\u00e8ne la Russie.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Dimension humaine | Fondation Canada-Ukraine | Soci\u00e9t\u00e9 civile | Infolettre (campagne)\" width=\"580\" height=\"326\" src=\"https:\/\/www.youtube.com\/embed\/ICPZIdAU7UY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 35%\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Qu&rsquo;il s&rsquo;agisse de prot\u00e9ger le patrimoine culturel ukrainien ou de fournir du mat\u00e9riel de hockey pour permettre aux enfants de retrouver un peu de normalit\u00e9, ces initiatives nous rappellent que la reconstruction de l&rsquo;Ukraine passe aussi par la protection de sa population, de son moral et de son avenir.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u2019est votre soutien qui rend toutes ces histoires possibles. Faites un don aujourd\u2019hui \u00e0 la Fondation Canada-Ukraine.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Derri\u00e8re chaque manchette se cache une histoire humaine.<\/strong><\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"http:\/\/weblink.donorperfect.com\/HumanDimension2026\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/05\/CUF_Flag-META_1350-Still17-FRA-1-819x1024.jpg\" alt=\"\" class=\"wp-image-26323 size-full\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background-color has-text-color has-background has-link-color wp-element-button\" href=\"http:\/\/weblink.donorperfect.com\/HumanDimension2026\" style=\"background-color:#be1c09\" target=\"_blank\" rel=\"noopener\">FAITES UN DON<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Pour faire un don\u00a0avec AMEX, PayPal ou Google\u00a0Pay, veuillez\u00a0<\/strong><a href=\"https:\/\/www.canadahelps.org\/fr\/dn\/146409\" target=\"_blank\" rel=\"noreferrer noopener\">visiter notre page\u00a0CanadaHelps<\/a><strong>.\u00a0<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>\ufeff<\/strong><strong>\u00c0 propos de la Fondation Canada-Ukraine (FCU)<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Cr\u00e9\u00e9e en 1995, la FCU jouit d\u2019un bilan solide concernant l\u2019assistance humanitaire qu\u2019elle fournit \u00e0 l\u2019Ukraine dans les domaines des soins de la sant\u00e9, de l\u2019\u00e9ducation et de la soci\u00e9t\u00e9 civile. La FCU travaille en collaboration avec des fournisseurs d\u2019aide en Ukraine, au Canada, et au-del\u00e0, afin de maximiser les retomb\u00e9es et la rentabilit\u00e9 de votre soutien.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les 13 et 14 mai, pendant plus de 48 heures, la Russie a men\u00e9 l&rsquo;une des attaques a\u00e9riennes les plus longues et les plus intenses depuis le d\u00e9but de l&rsquo;invasion \u00e0 grande \u00e9chelle en 2022. Pr\u00e8s de 1\u00a0600 drones et 60 missiles ont pris pour cible plus de 20 r\u00e9gions d\u2019Ukraine.\u00a0 Les reportages mettent l&rsquo;accent [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":26323,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[67],"tags":[],"class_list":["post-26321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-fr"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-21 22:28:48","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts\/26321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/comments?post=26321"}],"version-history":[{"count":1,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts\/26321\/revisions"}],"predecessor-version":[{"id":26326,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts\/26321\/revisions\/26326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/media\/26323"}],"wp:attachment":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/media?parent=26321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/categories?post=26321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/tags?post=26321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}