{"id":27576,"date":"2026-05-27T08:00:00","date_gmt":"2026-05-27T12:00:00","guid":{"rendered":"https:\/\/www.cufoundation.ca\/behind-every-headline-is-a-family-determined-to-keep-going\/"},"modified":"2026-06-30T23:28:50","modified_gmt":"2026-07-01T03:28:50","slug":"behind-every-headline-is-a-family-determined-to-keep-going","status":"publish","type":"post","link":"https:\/\/www.cufoundation.ca\/fr\/behind-every-headline-is-a-family-determined-to-keep-going\/","title":{"rendered":"Derri\u00e8re chaque manchette se cache une famille d\u00e9termin\u00e9e \u00e0 aller de l\u2019avant"},"content":{"rendered":"\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background-color has-text-color has-background has-link-color wp-element-button\" href=\"http:\/\/weblink.donorperfect.com\/HumanDimension2026\" style=\"background-color:#be1c09\" target=\"_blank\" rel=\"noopener\">FAITES UN DON<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Selon un r\u00e9cent rapport des Nations Unies\u00a0<strong>plus de 3 500 enfants<\/strong>\u00a0ont \u00e9t\u00e9 tu\u00e9s ou bless\u00e9s depuis le d\u00e9but de l\u2019invasion \u00e0 grande \u00e9chelle de l\u2019Ukraine par la Russie, et le nombre d\u2019enfants parmi les victimes a encore augment\u00e9 cette ann\u00e9e. Pour ces familles, la guerre n\u2019est pas simplement un \u00e9v\u00e9nement d\u00e9vastateur, mais il s\u2019agit d\u2019un combat quotidien pour prot\u00e9ger l\u2019enfance elle-m\u00eame.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quand des familles fuient la guerre, elles laissent derri\u00e8re elles bien plus que leur foyer. Pour les enfants qui vivent avec un handicap, ce sont aussi les \u00e9l\u00e9ments fragiles d\u2019un syst\u00e8me qui rendent le quotidien possible qui disparaissent : des th\u00e9rapeutes de confiance, la familiarit\u00e9 de leurs routines, des soins sp\u00e9cialis\u00e9s, un sentiment de s\u00e9curit\u00e9. En un instant, toutes ces ressources essentielles peuvent s\u2019\u00e9vanouir.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Dimension humaine | Fondation Canada-Ukraine | Dzherelo | Infolettre\" width=\"580\" height=\"326\" src=\"https:\/\/www.youtube.com\/embed\/FXN4GJnQW28?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Bas\u00e9 \u00e0 Lviv, le\u00a0<strong>Centre de r\u00e9adaptation Dzherelo<\/strong>\u00a0est une v\u00e9ritable bou\u00e9e de sauvetage pour les enfants et les jeunes vivant avec un handicap, et ce depuis bien avant l\u2019invasion \u00e0 grande \u00e9chelle. L\u2019organisme offre des services de r\u00e9adaptation et des programmes de jour essentiels aux familles. N\u00e9 en 1993 sous la forme d&rsquo;un petit groupe autofinanc\u00e9, le Centre s\u2019est d\u00e9velopp\u00e9 pour devenir bien plus que cela : un lieu o\u00f9 les enfants ayant des besoins complexes peuvent s\u2019\u00e9panouir, socialiser et profiter d&rsquo;une v\u00e9ritable qualit\u00e9 de vie au quotidien. Pour de nombreuses familles, Dzherelo est tout simplement irrempla\u00e7able.<\/p>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 35%\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong>La Fondation Canada-Ukraine soutient Dzherelo \u00e0 travers son partenariat \u00ab Druzi of Dzherelo \u00bb depuis 2019.<\/strong>\u00a0Au fil des ans, plus de 20 000 enfants, jeunes et familles ont pu b\u00e9n\u00e9ficier de services de r\u00e9adaptation et de services sociaux. Depuis le d\u00e9but de l\u2019invasion \u00e0 grande \u00e9chelle, le centre a \u00e9largi la port\u00e9e de son champ d\u2019action \u00e0 travers l\u2019ouest de l\u2019Ukraine et au-del\u00e0, offrant une aide d&rsquo;urgente et une assistance humanitaire \u00e0 30 000 personnes suppl\u00e9mentaires gr\u00e2ce \u00e0 ses programmes. Cette expansion n\u2019est possible que gr\u00e2ce \u00e0 des donatrices et donateurs tels que vous<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/05\/CUF_HumanStory-FULL_UA_Still05GIRL-1350-FRA-819x1024.jpg\" alt=\"\" class=\"wp-image-27578 size-full\" srcset=\"https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/05\/CUF_HumanStory-FULL_UA_Still05GIRL-1350-FRA-819x1024.jpg 819w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/05\/CUF_HumanStory-FULL_UA_Still05GIRL-1350-FRA-240x300.jpg 240w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/05\/CUF_HumanStory-FULL_UA_Still05GIRL-1350-FRA-768x960.jpg 768w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/05\/CUF_HumanStory-FULL_UA_Still05GIRL-1350-FRA.jpg 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Derri\u00e8re chaque manchette se cache une histoire humaine.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Votre soutien aide les personnes qui se cachent derri\u00e8re les nouvelles.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background-color has-text-color has-background has-link-color wp-element-button\" href=\"http:\/\/weblink.donorperfect.com\/HumanDimension2026\" style=\"background-color:#be1c09\" target=\"_blank\" rel=\"noopener\">FAITES UN DON<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Pour faire un don\u00a0avec AMEX, PayPal ou Google\u00a0Pay, veuillez\u00a0<\/strong><a href=\"https:\/\/www.canadahelps.org\/fr\/dn\/146409\" target=\"_blank\" rel=\"noreferrer noopener\">visiter notre page\u00a0CanadaHelps<\/a><strong>.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>\u00c0 propos de la Fondation Canada-Ukraine (FCU)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00e9\u00e9e en 1995, la FCU jouit d\u2019un bilan solide concernant l\u2019assistance humanitaire qu\u2019elle fournit \u00e0 l\u2019Ukraine dans les domaines des soins de la sant\u00e9, de l\u2019\u00e9ducation et de la soci\u00e9t\u00e9 civile. La FCU travaille en collaboration avec des fournisseurs d\u2019aide en Ukraine, au Canada, et au-del\u00e0, afin de maximiser les retomb\u00e9es et la rentabilit\u00e9 de votre soutien.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon un r\u00e9cent rapport des Nations Unies\u00a0plus de 3 500 enfants\u00a0ont \u00e9t\u00e9 tu\u00e9s ou bless\u00e9s depuis le d\u00e9but de l\u2019invasion \u00e0 grande \u00e9chelle de l\u2019Ukraine par la Russie, et le nombre d\u2019enfants parmi les victimes a encore augment\u00e9 cette ann\u00e9e. Pour ces familles, la guerre n\u2019est pas simplement un \u00e9v\u00e9nement d\u00e9vastateur, mais il s\u2019agit d\u2019un [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":27578,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[67],"tags":[],"class_list":["post-27576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-fr"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-21 22:31:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts\/27576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/comments?post=27576"}],"version-history":[{"count":1,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts\/27576\/revisions"}],"predecessor-version":[{"id":27581,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts\/27576\/revisions\/27581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/media\/27578"}],"wp:attachment":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/media?parent=27576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/categories?post=27576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/tags?post=27576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}