{"id":27604,"date":"2026-06-04T08:00:00","date_gmt":"2026-06-04T12:00:00","guid":{"rendered":"https:\/\/www.cufoundation.ca\/behind-every-headline-is-determination\/"},"modified":"2026-06-30T23:51:20","modified_gmt":"2026-07-01T03:51:20","slug":"behind-every-headline-is-determination","status":"publish","type":"post","link":"https:\/\/www.cufoundation.ca\/fr\/behind-every-headline-is-determination\/","title":{"rendered":"Derri\u00e8re chaque manchette se cache une d\u00e9termination extraordinaire"},"content":{"rendered":"\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background-color has-text-color has-background has-link-color wp-element-button\" href=\"http:\/\/weblink.donorperfect.com\/HumanDimension2026\" style=\"background-color:#be1c09\" target=\"_blank\" rel=\"noopener\">FAITES UN DON<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Un ancien combattant qui fait ses premiers pas avec une proth\u00e8se.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une th\u00e9rapeute qui aide un patient \u00e0 retrouver son autonomie.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un chirurgien qui partage ses nouvelles comp\u00e9tences avec ses coll\u00e8gues \u00e0 travers toute l\u2019Ukraine.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derri\u00e8re chacune de ces histoires se cache un parcours de r\u00e9tablissement, de pers\u00e9v\u00e9rance et le travail acharn\u00e9 de personnes qui rendent ces progr\u00e8s possibles.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Dimension humaine | Fondation Canada-Ukraine | Unbroken | Infolettre\" width=\"580\" height=\"326\" src=\"https:\/\/www.youtube.com\/embed\/jxNZIoImh2E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis le d\u00e9but de l&rsquo;invasion \u00e0 grande \u00e9chelle de l&rsquo;Ukraine par la Russie, plus de 24 000 personnes ukrainiennes bless\u00e9es ont re\u00e7u des soins gr\u00e2ce \u00e0\u00a0<strong>UNBROKEN<\/strong>, un centre de r\u00e9adaptation \u00e0 Lviv devenu un chef de file en mati\u00e8re de r\u00e9tablissement, de r\u00e9adaptation et d&rsquo;innovation.\u00a0Chaque jour, des patients et des professionnels de la sant\u00e9 travaillent ensemble pour accomplir quelque chose d&rsquo;extraordinaire : retrouver leur mobilit\u00e9, reb\u00e2tir leur confiance et aider des personnes \u00e0 reprendre leur place aupr\u00e8s de leur famille, dans leur carri\u00e8re et au sein de leur communaut\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce au soutien de la Fondation Canada-Ukraine et de ses partenaires, UNBROKEN a \u00e9largi l&rsquo;acc\u00e8s \u00e0 des \u00e9quipements sp\u00e9cialis\u00e9s de r\u00e9adaptation, \u00e0 des syst\u00e8mes th\u00e9rapeutiques avanc\u00e9s et \u00e0 des formations professionnelles. Des professionnels de la sant\u00e9 d&rsquo;Ukraine se sont \u00e9galement rendus au Canada afin de perfectionner leur expertise en soins proth\u00e9tiques, en chirurgie reconstructive, en r\u00e9adaptation et en neurophysiologie, pour ensuite ramener ces connaissances en Ukraine et en faire b\u00e9n\u00e9ficier des patients partout au pays.<\/p>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 35%\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Le r\u00e9tablissement se mesure par des \u00e9tapes importantes : un premier pas, un meilleur \u00e9quilibre, une autonomie retrouv\u00e9e et la confiance n\u00e9cessaire pour aller de l&rsquo;avant.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derri\u00e8re chaque manchette se trouve une personne qui choisit de ne pas abandonner.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et derri\u00e8re chaque pas vers l&rsquo;avant se trouve une communaut\u00e9 de donatrices et donateurs et de partenaires qui contribuent \u00e0 rendre ces progr\u00e8s possibles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Faites une diff\u00e9rence. Faites un don d\u00e8s aujourd&rsquo;hui.<\/strong><\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/06\/CUF_Navy-META_1080-Veteran-FRA-1024x1024.jpg\" alt=\"\" class=\"wp-image-27606 size-full\" srcset=\"https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/06\/CUF_Navy-META_1080-Veteran-FRA-1024x1024.jpg 1024w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/06\/CUF_Navy-META_1080-Veteran-FRA-300x300.jpg 300w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/06\/CUF_Navy-META_1080-Veteran-FRA-150x150.jpg 150w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/06\/CUF_Navy-META_1080-Veteran-FRA-768x768.jpg 768w, https:\/\/www.cufoundation.ca\/wp-content\/uploads\/2026\/06\/CUF_Navy-META_1080-Veteran-FRA.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background-color has-text-color has-background has-link-color wp-element-button\" href=\"http:\/\/weblink.donorperfect.com\/HumanDimension2026\" style=\"background-color:#be1c09\" target=\"_blank\" rel=\"noopener\">FAITES UN DON<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Pour faire un don\u00a0avec AMEX, PayPal ou Google\u00a0Pay, veuillez\u00a0<\/strong><a href=\"https:\/\/www.canadahelps.org\/fr\/dn\/146409\" target=\"_blank\" rel=\"noreferrer noopener\">visiter notre page\u00a0CanadaHelps<\/a><strong>.\u00a0<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>\ufeff<\/strong><strong>\u00c0 propos de la Fondation Canada-Ukraine (FCU)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00e9\u00e9e en 1995, la FCU jouit d\u2019un bilan solide concernant l\u2019assistance humanitaire qu\u2019elle fournit \u00e0 l\u2019Ukraine dans les domaines des soins de la sant\u00e9, de l\u2019\u00e9ducation et de la soci\u00e9t\u00e9 civile. La FCU travaille en collaboration avec des fournisseurs d\u2019aide en Ukraine, au Canada, et au-del\u00e0, afin de maximiser les retomb\u00e9es et la rentabilit\u00e9 de votre soutien.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un ancien combattant qui fait ses premiers pas avec une proth\u00e8se.&nbsp; Une th\u00e9rapeute qui aide un patient \u00e0 retrouver son autonomie.&nbsp; Un chirurgien qui partage ses nouvelles comp\u00e9tences avec ses coll\u00e8gues \u00e0 travers toute l\u2019Ukraine.&nbsp; Derri\u00e8re chacune de ces histoires se cache un parcours de r\u00e9tablissement, de pers\u00e9v\u00e9rance et le travail acharn\u00e9 de personnes qui [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":27606,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[67],"tags":[],"class_list":["post-27604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-fr"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-21 22:50:27","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts\/27604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/comments?post=27604"}],"version-history":[{"count":1,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts\/27604\/revisions"}],"predecessor-version":[{"id":27609,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/posts\/27604\/revisions\/27609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/media\/27606"}],"wp:attachment":[{"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/media?parent=27604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/categories?post=27604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cufoundation.ca\/fr\/wp-json\/wp\/v2\/tags?post=27604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}